{"id":305,"date":"2016-06-23T17:40:56","date_gmt":"2016-06-23T15:40:56","guid":{"rendered":"http:\/\/nick-heilborn.de\/rallye\/?p=305"},"modified":"2016-10-09T18:10:59","modified_gmt":"2016-10-09T16:10:59","slug":"39-landsbergrallye-18-06-2016","status":"publish","type":"post","link":"https:\/\/www.ifm-motorsport.de\/start\/39-landsbergrallye-18-06-2016\/","title":{"rendered":"39. Landsbergrallye, 18.06.2016"},"content":{"rendered":"<p>2. Platz Klasse F3B, 19. Gesamt!<\/p>\n<p>Neues Spiel, neues Gl\u00fcck.<\/p>\n<p>Unter diesem Motto gingen Co-Pilot Benjamin Melde und ich am letzten Wochenende in Meiningen an den Start.<\/p>\n<p>Letztes Jahr noch auf WP 1 mit defektem K\u00fchler ausgefallen (damals mit Tim Gleisberg als Navigator auf dem hei\u00dfen Sitz), hofften wir nun, dass es die Landsberg-Rallye dieses Jahr besser mit uns meint.<\/p>\n<p>Und sie tat es!<\/p>\n<p>In Anbetracht dessen, dass wir in unserer Klasse ausschlie\u00dflich deutlich st\u00e4rkere BMW M3 als Gegner hatten, haben wir von Beginn an keine realistischen\u00a0Erwartungen in eine gute Platzierung gesetzt. Deshalb gingen wir auch direkt wieder mit unseren ebenfalls unterlegenen, aber bew\u00e4hrten Serienreifen an den Start und wollten einfach ein wenig Spa\u00df haben und schauen, wo wir uns letztendlich einsortieren.<\/p>\n<p>Zu unserer eigenen \u00dcberraschung konnten wir uns von Beginn an auf Platz 3 in der Klasse behaupten und gaben diese Position auch bis zur vorletzten WP nicht mehr ab. Durch den Ausfall\u00a0eines vor uns liegenden M3-Teams auf der letzten WP, rutschten wir sogar noch um einen Platz nach vorn und beendeten die Rallye auf Rang 2 in der Klasse F3B und Rang 19 von 69 Startern im Gesamtklassement.<\/p>\n<p>Damit h\u00e4tten wir im Vorfeld definitiv nicht gerechnet! Aber vor Allem beim vorherrschenden wechselhaften Wetter -Sonnenschein und Regen wechselten sich stetig\u00a0ab- konnten wir unser Leistungsmanko von \u00fcber 100 PS durch entsprechend engagierte Fahrweise scheinbar einigerma\u00dfen ausgleichen.<\/p>\n<p>Sehr\u00a0zufrieden reisten wir aus Meiningen\u00a0ab und beginnen\u00a0zugleich mit den Vorbereitungen f\u00fcr die\u00a0\u00a0Weidaer Osterburg-Rallye, am 25.06.2016<\/p>\n","protected":false},"excerpt":{"rendered":"<p>2. Platz Klasse F3B, 19. Gesamt! Neues Spiel, neues Gl\u00fcck. Unter diesem Motto gingen Co-Pilot Benjamin Melde und ich am letzten Wochenende in Meiningen an den Start. Letztes Jahr noch auf WP 1 mit defektem K\u00fchler ausgefallen (damals mit Tim Gleisberg als Navigator auf dem hei\u00dfen Sitz), hofften wir nun, dass es die Landsberg-Rallye dieses [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":306,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[8],"tags":[4],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v21.8.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>39. Landsbergrallye, 18.06.2016 - IFM-Motorsport.de<\/title>\n<meta name=\"description\" content=\"nick heilborn rallye ihr-finanzfachmann.de\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.ifm-motorsport.de\/start\/39-landsbergrallye-18-06-2016\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"39. Landsbergrallye, 18.06.2016 - IFM-Motorsport.de\" \/>\n<meta property=\"og:description\" content=\"nick heilborn rallye ihr-finanzfachmann.de\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.ifm-motorsport.de\/start\/39-landsbergrallye-18-06-2016\/\" \/>\n<meta property=\"og:site_name\" content=\"IFM-Motorsport.de\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Vermoegensberatung.Hermsdorf\" \/>\n<meta property=\"article:published_time\" content=\"2016-06-23T15:40:56+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2016-10-09T16:10:59+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.ifm-motorsport.de\/start\/wp-content\/uploads\/2016\/06\/IMG_3623-Kopie-1024x683.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"683\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"1\u00a0Minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.ifm-motorsport.de\/start\/39-landsbergrallye-18-06-2016\/\",\"url\":\"https:\/\/www.ifm-motorsport.de\/start\/39-landsbergrallye-18-06-2016\/\",\"name\":\"39. Landsbergrallye, 18.06.2016 - IFM-Motorsport.de\",\"isPartOf\":{\"@id\":\"https:\/\/www.ifm-motorsport.de\/start\/#website\"},\"datePublished\":\"2016-06-23T15:40:56+00:00\",\"dateModified\":\"2016-10-09T16:10:59+00:00\",\"author\":{\"@id\":\"https:\/\/www.ifm-motorsport.de\/start\/#\/schema\/person\/eff8cb1eeb947fc2be384f468211b0fb\"},\"description\":\"nick heilborn rallye ihr-finanzfachmann.de\",\"breadcrumb\":{\"@id\":\"https:\/\/www.ifm-motorsport.de\/start\/39-landsbergrallye-18-06-2016\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.ifm-motorsport.de\/start\/39-landsbergrallye-18-06-2016\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.ifm-motorsport.de\/start\/39-landsbergrallye-18-06-2016\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.ifm-motorsport.de\/start\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"39. Landsbergrallye, 18.06.2016\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.ifm-motorsport.de\/start\/#website\",\"url\":\"https:\/\/www.ifm-motorsport.de\/start\/\",\"name\":\"IFM-Motorsport.de\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.ifm-motorsport.de\/start\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"de\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.ifm-motorsport.de\/start\/#\/schema\/person\/eff8cb1eeb947fc2be384f468211b0fb\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/www.ifm-motorsport.de\/start\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/d2e5ceb10b271dc096153cf6d0afa206?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/d2e5ceb10b271dc096153cf6d0afa206?s=96&d=mm&r=g\",\"caption\":\"admin\"},\"url\":\"https:\/\/www.ifm-motorsport.de\/start\/author\/admin\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"39. Landsbergrallye, 18.06.2016 - IFM-Motorsport.de","description":"nick heilborn rallye ihr-finanzfachmann.de","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.ifm-motorsport.de\/start\/39-landsbergrallye-18-06-2016\/","og_locale":"de_DE","og_type":"article","og_title":"39. Landsbergrallye, 18.06.2016 - IFM-Motorsport.de","og_description":"nick heilborn rallye ihr-finanzfachmann.de","og_url":"https:\/\/www.ifm-motorsport.de\/start\/39-landsbergrallye-18-06-2016\/","og_site_name":"IFM-Motorsport.de","article_publisher":"https:\/\/www.facebook.com\/Vermoegensberatung.Hermsdorf","article_published_time":"2016-06-23T15:40:56+00:00","article_modified_time":"2016-10-09T16:10:59+00:00","og_image":[{"width":1024,"height":683,"url":"https:\/\/www.ifm-motorsport.de\/start\/wp-content\/uploads\/2016\/06\/IMG_3623-Kopie-1024x683.jpg","type":"image\/jpeg"}],"author":"admin","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"admin","Gesch\u00e4tzte Lesezeit":"1\u00a0Minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.ifm-motorsport.de\/start\/39-landsbergrallye-18-06-2016\/","url":"https:\/\/www.ifm-motorsport.de\/start\/39-landsbergrallye-18-06-2016\/","name":"39. Landsbergrallye, 18.06.2016 - IFM-Motorsport.de","isPartOf":{"@id":"https:\/\/www.ifm-motorsport.de\/start\/#website"},"datePublished":"2016-06-23T15:40:56+00:00","dateModified":"2016-10-09T16:10:59+00:00","author":{"@id":"https:\/\/www.ifm-motorsport.de\/start\/#\/schema\/person\/eff8cb1eeb947fc2be384f468211b0fb"},"description":"nick heilborn rallye ihr-finanzfachmann.de","breadcrumb":{"@id":"https:\/\/www.ifm-motorsport.de\/start\/39-landsbergrallye-18-06-2016\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.ifm-motorsport.de\/start\/39-landsbergrallye-18-06-2016\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.ifm-motorsport.de\/start\/39-landsbergrallye-18-06-2016\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.ifm-motorsport.de\/start\/"},{"@type":"ListItem","position":2,"name":"39. Landsbergrallye, 18.06.2016"}]},{"@type":"WebSite","@id":"https:\/\/www.ifm-motorsport.de\/start\/#website","url":"https:\/\/www.ifm-motorsport.de\/start\/","name":"IFM-Motorsport.de","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.ifm-motorsport.de\/start\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"de"},{"@type":"Person","@id":"https:\/\/www.ifm-motorsport.de\/start\/#\/schema\/person\/eff8cb1eeb947fc2be384f468211b0fb","name":"admin","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.ifm-motorsport.de\/start\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/d2e5ceb10b271dc096153cf6d0afa206?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/d2e5ceb10b271dc096153cf6d0afa206?s=96&d=mm&r=g","caption":"admin"},"url":"https:\/\/www.ifm-motorsport.de\/start\/author\/admin\/"}]}},"jetpack_featured_media_url":"https:\/\/www.ifm-motorsport.de\/start\/wp-content\/uploads\/2016\/06\/IMG_3623-Kopie.jpg","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.ifm-motorsport.de\/start\/wp-json\/wp\/v2\/posts\/305"}],"collection":[{"href":"https:\/\/www.ifm-motorsport.de\/start\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ifm-motorsport.de\/start\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ifm-motorsport.de\/start\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ifm-motorsport.de\/start\/wp-json\/wp\/v2\/comments?post=305"}],"version-history":[{"count":6,"href":"https:\/\/www.ifm-motorsport.de\/start\/wp-json\/wp\/v2\/posts\/305\/revisions"}],"predecessor-version":[{"id":314,"href":"https:\/\/www.ifm-motorsport.de\/start\/wp-json\/wp\/v2\/posts\/305\/revisions\/314"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ifm-motorsport.de\/start\/wp-json\/wp\/v2\/media\/306"}],"wp:attachment":[{"href":"https:\/\/www.ifm-motorsport.de\/start\/wp-json\/wp\/v2\/media?parent=305"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ifm-motorsport.de\/start\/wp-json\/wp\/v2\/categories?post=305"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ifm-motorsport.de\/start\/wp-json\/wp\/v2\/tags?post=305"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}